{"id":15783,"date":"2024-09-06T23:18:19","date_gmt":"2024-09-06T21:18:19","guid":{"rendered":"https:\/\/dipendenzepatologiche.apg23.org\/area-prevenzione\/?post_type=dt_portfolio&#038;p=15783"},"modified":"2024-09-06T23:23:17","modified_gmt":"2024-09-06T21:23:17","slug":"parlami-dellamore-primaria","status":"publish","type":"dt_portfolio","link":"https:\/\/cpg23.org\/area-prevenzione\/percorso\/parlami-dellamore-primaria\/","title":{"rendered":"Parlami dell\u2019amore (Primaria)"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"15783\" class=\"elementor elementor-15783\" data-elementor-post-type=\"dt_portfolio\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b9f318e e-flex e-con-boxed e-con e-parent\" data-id=\"b9f318e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e72ccc0 elementor-widget elementor-widget-heading\" data-id=\"e72ccc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Educazione affettiva, sessualit\u00e0, relazioni.<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47e3013 elementor-widget elementor-widget-spacer\" data-id=\"47e3013\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c72f54 elementor-widget elementor-widget-text-editor\" data-id=\"7c72f54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>ll percorso si propone di favorire nei bambini un approccio positivo con se stessi e con la propria dimensione relazionale ed affettiva.<\/p><p>Guidati da un esperto, insieme con l\u2019insegnante, si affronteranno temi come la conoscenza del proprio corpo, la dimensione riproduttiva-sessuale e la dimensione relazionale ad essa correlata.<\/p><p>I genitori saranno coinvolti prima e dopo con incontri specifici.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f24c90d elementor-widget elementor-widget-spacer\" data-id=\"f24c90d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3432fd elementor-align-right elementor-widget elementor-widget-button\" data-id=\"e3432fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">PDF<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Educazione affettiva, sessualit\u00e0, relazioni.<\/p>\n","protected":false},"author":2,"featured_media":15786,"comment_status":"closed","ping_status":"closed","template":"","dt_portfolio_category":[146],"dt_portfolio_tags":[240,210,244,237,243,233,236],"provincie":[139],"target":[169,170,171],"class_list":["post-15783","dt_portfolio","type-dt_portfolio","status-publish","has-post-thumbnail","hentry","dt_portfolio_category-alfabetizzazione-emotiva-affettivita-sessualita","dt_portfolio_tags-aducazione-affettiva","dt_portfolio_tags-affettivita","dt_portfolio_tags-alfabetizzazione-emotiva","dt_portfolio_tags-corpo","dt_portfolio_tags-educazione-emozionale","dt_portfolio_tags-relazioni","dt_portfolio_tags-sessualita","provincie-vicenza","target-classe-3","target-classe-4","target-classe-5"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Parlami dell\u2019amore (Primaria) - Area Prevenzione Coop.CPG23<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Parlami dell\u2019amore (Primaria) - Area Prevenzione Coop.CPG23\" \/>\n<meta property=\"og:description\" content=\"Educazione affettiva, sessualit\u00e0, relazioni.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cpg23.org\/area-prevenzione\/percorso\/parlami-dellamore-primaria\/\" \/>\n<meta property=\"og:site_name\" content=\"Area Prevenzione Coop.CPG23\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dipend.23\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-06T21:23:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cpg23.org\/area-prevenzione\/wp-content\/uploads\/2024\/09\/parlami-dellamore-primaria.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/percorso\\\/parlami-dellamore-primaria\\\/\",\"url\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/percorso\\\/parlami-dellamore-primaria\\\/\",\"name\":\"Parlami dell\u2019amore (Primaria) - Area Prevenzione Coop.CPG23\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/percorso\\\/parlami-dellamore-primaria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/percorso\\\/parlami-dellamore-primaria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/parlami-dellamore-primaria.png\",\"datePublished\":\"2024-09-06T21:18:19+00:00\",\"dateModified\":\"2024-09-06T21:23:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/percorso\\\/parlami-dellamore-primaria\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/percorso\\\/parlami-dellamore-primaria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/percorso\\\/parlami-dellamore-primaria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/parlami-dellamore-primaria.png\",\"contentUrl\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/parlami-dellamore-primaria.png\",\"width\":800,\"height\":600,\"caption\":\"Percorso Parlami dell'amore (primaria)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/percorso\\\/parlami-dellamore-primaria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aree Tematiche\",\"item\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/percorso\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Parlami dell\u2019amore (Primaria)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/#website\",\"url\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/\",\"name\":\"Area Prevenzione Coop.CPG23\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/#organization\",\"name\":\"Area Prevenzione Coop.CPG23\",\"url\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/LOGO_CPG23_ORIZ-1.png\",\"contentUrl\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/LOGO_CPG23_ORIZ-1.png\",\"width\":1593,\"height\":413,\"caption\":\"Area Prevenzione Coop.CPG23\"},\"image\":{\"@id\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dipend.23\",\"https:\\\/\\\/www.instagram.com\\\/dipend.23\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Parlami dell\u2019amore (Primaria) - Area Prevenzione Coop.CPG23","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"Parlami dell\u2019amore (Primaria) - Area Prevenzione Coop.CPG23","og_description":"Educazione affettiva, sessualit\u00e0, relazioni.","og_url":"https:\/\/cpg23.org\/area-prevenzione\/percorso\/parlami-dellamore-primaria\/","og_site_name":"Area Prevenzione Coop.CPG23","article_publisher":"https:\/\/www.facebook.com\/dipend.23","article_modified_time":"2024-09-06T21:23:17+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/cpg23.org\/area-prevenzione\/wp-content\/uploads\/2024\/09\/parlami-dellamore-primaria.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cpg23.org\/area-prevenzione\/percorso\/parlami-dellamore-primaria\/","url":"https:\/\/cpg23.org\/area-prevenzione\/percorso\/parlami-dellamore-primaria\/","name":"Parlami dell\u2019amore (Primaria) - Area Prevenzione Coop.CPG23","isPartOf":{"@id":"https:\/\/cpg23.org\/area-prevenzione\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cpg23.org\/area-prevenzione\/percorso\/parlami-dellamore-primaria\/#primaryimage"},"image":{"@id":"https:\/\/cpg23.org\/area-prevenzione\/percorso\/parlami-dellamore-primaria\/#primaryimage"},"thumbnailUrl":"https:\/\/cpg23.org\/area-prevenzione\/wp-content\/uploads\/2024\/09\/parlami-dellamore-primaria.png","datePublished":"2024-09-06T21:18:19+00:00","dateModified":"2024-09-06T21:23:17+00:00","breadcrumb":{"@id":"https:\/\/cpg23.org\/area-prevenzione\/percorso\/parlami-dellamore-primaria\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cpg23.org\/area-prevenzione\/percorso\/parlami-dellamore-primaria\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cpg23.org\/area-prevenzione\/percorso\/parlami-dellamore-primaria\/#primaryimage","url":"https:\/\/cpg23.org\/area-prevenzione\/wp-content\/uploads\/2024\/09\/parlami-dellamore-primaria.png","contentUrl":"https:\/\/cpg23.org\/area-prevenzione\/wp-content\/uploads\/2024\/09\/parlami-dellamore-primaria.png","width":800,"height":600,"caption":"Percorso Parlami dell'amore (primaria)"},{"@type":"BreadcrumbList","@id":"https:\/\/cpg23.org\/area-prevenzione\/percorso\/parlami-dellamore-primaria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cpg23.org\/area-prevenzione\/"},{"@type":"ListItem","position":2,"name":"Aree Tematiche","item":"https:\/\/cpg23.org\/area-prevenzione\/percorso\/"},{"@type":"ListItem","position":3,"name":"Parlami dell\u2019amore (Primaria)"}]},{"@type":"WebSite","@id":"https:\/\/cpg23.org\/area-prevenzione\/#website","url":"https:\/\/cpg23.org\/area-prevenzione\/","name":"Area Prevenzione Coop.CPG23","description":"","publisher":{"@id":"https:\/\/cpg23.org\/area-prevenzione\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cpg23.org\/area-prevenzione\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cpg23.org\/area-prevenzione\/#organization","name":"Area Prevenzione Coop.CPG23","url":"https:\/\/cpg23.org\/area-prevenzione\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cpg23.org\/area-prevenzione\/#\/schema\/logo\/image\/","url":"https:\/\/cpg23.org\/area-prevenzione\/wp-content\/uploads\/2021\/09\/LOGO_CPG23_ORIZ-1.png","contentUrl":"https:\/\/cpg23.org\/area-prevenzione\/wp-content\/uploads\/2021\/09\/LOGO_CPG23_ORIZ-1.png","width":1593,"height":413,"caption":"Area Prevenzione Coop.CPG23"},"image":{"@id":"https:\/\/cpg23.org\/area-prevenzione\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dipend.23","https:\/\/www.instagram.com\/dipend.23\/"]}]}},"_links":{"self":[{"href":"https:\/\/cpg23.org\/area-prevenzione\/wp-json\/wp\/v2\/dt_portfolio\/15783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cpg23.org\/area-prevenzione\/wp-json\/wp\/v2\/dt_portfolio"}],"about":[{"href":"https:\/\/cpg23.org\/area-prevenzione\/wp-json\/wp\/v2\/types\/dt_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/cpg23.org\/area-prevenzione\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cpg23.org\/area-prevenzione\/wp-json\/wp\/v2\/comments?post=15783"}],"version-history":[{"count":5,"href":"https:\/\/cpg23.org\/area-prevenzione\/wp-json\/wp\/v2\/dt_portfolio\/15783\/revisions"}],"predecessor-version":[{"id":15790,"href":"https:\/\/cpg23.org\/area-prevenzione\/wp-json\/wp\/v2\/dt_portfolio\/15783\/revisions\/15790"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cpg23.org\/area-prevenzione\/wp-json\/wp\/v2\/media\/15786"}],"wp:attachment":[{"href":"https:\/\/cpg23.org\/area-prevenzione\/wp-json\/wp\/v2\/media?parent=15783"}],"wp:term":[{"taxonomy":"dt_portfolio_category","embeddable":true,"href":"https:\/\/cpg23.org\/area-prevenzione\/wp-json\/wp\/v2\/dt_portfolio_category?post=15783"},{"taxonomy":"dt_portfolio_tags","embeddable":true,"href":"https:\/\/cpg23.org\/area-prevenzione\/wp-json\/wp\/v2\/dt_portfolio_tags?post=15783"},{"taxonomy":"provincie","embeddable":true,"href":"https:\/\/cpg23.org\/area-prevenzione\/wp-json\/wp\/v2\/provincie?post=15783"},{"taxonomy":"target","embeddable":true,"href":"https:\/\/cpg23.org\/area-prevenzione\/wp-json\/wp\/v2\/target?post=15783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}