{"id":15797,"date":"2024-09-06T23:32:32","date_gmt":"2024-09-06T21:32:32","guid":{"rendered":"https:\/\/dipendenzepatologiche.apg23.org\/area-prevenzione\/?post_type=dt_portfolio&#038;p=15797"},"modified":"2024-09-06T23:34:49","modified_gmt":"2024-09-06T21:34:49","slug":"piacere-felicita","status":"publish","type":"dt_portfolio","link":"https:\/\/cpg23.org\/area-prevenzione\/percorso\/piacere-felicita\/","title":{"rendered":"Piacere. Felicit\u00e0."},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"15797\" class=\"elementor elementor-15797\" data-elementor-post-type=\"dt_portfolio\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b9f318e e-flex e-con-boxed e-con e-parent\" data-id=\"b9f318e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e72ccc0 elementor-widget elementor-widget-heading\" data-id=\"e72ccc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Giovani, affettivit\u00e0 e sessualit\u00e0.<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47e3013 elementor-widget elementor-widget-spacer\" data-id=\"47e3013\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c72f54 elementor-widget elementor-widget-text-editor\" data-id=\"7c72f54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ci sono sfide peculiari dell\u2019et\u00e0 adolescenziale che accompagnano i ragazzi e ragazze nel loro percorso verso l\u2019et\u00e0 adulta. Tutti e tutte le abbiamo attraversate, ma oggi ci sono elementi di novit\u00e0 che non possono essere trascurati. Tra questi, a titolo esemplificativo, lo sviluppo e l\u2019ampia diffusione delle nuove tecnologie, la congiuntura storica di grande crisi, non solo economica, ma anche bellica, climatica, lavorativa, una visione del futuro orientata sempre meno alla speranza e sempre pi\u00f9 al pragmatismo individualista, la possibilit\u00e0 di procreare in modo disgiunto dai corpi, la sempre maggiore liquidit\u00e0 dei legami sociali e familiari.\u00a0<\/p><p>Come educatori ci chiediamo come accompagnare le giovani generazioni nella ricerca del proprio ben-essere affettivo e sessuale nel contesto attuale. La traiettoria che ci guida individua nella sessualit\u00e0 un \u00abdono\u00bb, non un tanto un \u00abproblema\u00bb.\u00a0<\/p><p>Ci poniamo in dialogo con i giovani, non con riposte preconfezionate, ma condividendo con loro la ricerca di cosa siano la felicit\u00e0 e il piacere, sostenendoli nel bisogno comune di comprendere le contraddizioni che abitano la realt\u00e0 attuale, alla ricerca di punti di riferimento per affrontare le sfide di questa meravigliosa quanto impegnativa et\u00e0 della vita.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f24c90d elementor-widget elementor-widget-spacer\" data-id=\"f24c90d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3432fd elementor-align-right elementor-widget elementor-widget-button\" data-id=\"e3432fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">PDF<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Giovani, affettivit\u00e0 e sessualit\u00e0.<\/p>\n","protected":false},"author":2,"featured_media":15798,"comment_status":"closed","ping_status":"closed","template":"","dt_portfolio_category":[146],"dt_portfolio_tags":[252,240,210,244,237,243,253,254,233,236],"provincie":[134,158],"target":[142],"class_list":["post-15797","dt_portfolio","type-dt_portfolio","status-publish","has-post-thumbnail","hentry","dt_portfolio_category-alfabetizzazione-emotiva-affettivita-sessualita","dt_portfolio_tags-adolescenza","dt_portfolio_tags-aducazione-affettiva","dt_portfolio_tags-affettivita","dt_portfolio_tags-alfabetizzazione-emotiva","dt_portfolio_tags-corpo","dt_portfolio_tags-educazione-emozionale","dt_portfolio_tags-felicita","dt_portfolio_tags-piacere","dt_portfolio_tags-relazioni","dt_portfolio_tags-sessualita","provincie-lodi","provincie-milano","target-secondaria-di-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Piacere. Felicit\u00e0. - Area Prevenzione Coop.CPG23<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Piacere. Felicit\u00e0. - Area Prevenzione Coop.CPG23\" \/>\n<meta property=\"og:description\" content=\"Giovani, affettivit\u00e0 e sessualit\u00e0.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cpg23.org\/area-prevenzione\/percorso\/piacere-felicita\/\" \/>\n<meta property=\"og:site_name\" content=\"Area Prevenzione Coop.CPG23\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dipend.23\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-06T21:34:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cpg23.org\/area-prevenzione\/wp-content\/uploads\/2024\/09\/piacere-felicita.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/percorso\\\/piacere-felicita\\\/\",\"url\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/percorso\\\/piacere-felicita\\\/\",\"name\":\"Piacere. Felicit\u00e0. - Area Prevenzione Coop.CPG23\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/percorso\\\/piacere-felicita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/percorso\\\/piacere-felicita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/piacere-felicita.png\",\"datePublished\":\"2024-09-06T21:32:32+00:00\",\"dateModified\":\"2024-09-06T21:34:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/percorso\\\/piacere-felicita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/percorso\\\/piacere-felicita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/percorso\\\/piacere-felicita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/piacere-felicita.png\",\"contentUrl\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/piacere-felicita.png\",\"width\":800,\"height\":600,\"caption\":\"Percorso Piacere, felicita\u0300\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/percorso\\\/piacere-felicita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aree Tematiche\",\"item\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/percorso\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Piacere. Felicit\u00e0.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/#website\",\"url\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/\",\"name\":\"Area Prevenzione Coop.CPG23\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/#organization\",\"name\":\"Area Prevenzione Coop.CPG23\",\"url\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/LOGO_CPG23_ORIZ-1.png\",\"contentUrl\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/LOGO_CPG23_ORIZ-1.png\",\"width\":1593,\"height\":413,\"caption\":\"Area Prevenzione Coop.CPG23\"},\"image\":{\"@id\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dipend.23\",\"https:\\\/\\\/www.instagram.com\\\/dipend.23\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Piacere. Felicit\u00e0. - Area Prevenzione Coop.CPG23","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"Piacere. Felicit\u00e0. - Area Prevenzione Coop.CPG23","og_description":"Giovani, affettivit\u00e0 e sessualit\u00e0.","og_url":"https:\/\/cpg23.org\/area-prevenzione\/percorso\/piacere-felicita\/","og_site_name":"Area Prevenzione Coop.CPG23","article_publisher":"https:\/\/www.facebook.com\/dipend.23","article_modified_time":"2024-09-06T21:34:49+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/cpg23.org\/area-prevenzione\/wp-content\/uploads\/2024\/09\/piacere-felicita.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cpg23.org\/area-prevenzione\/percorso\/piacere-felicita\/","url":"https:\/\/cpg23.org\/area-prevenzione\/percorso\/piacere-felicita\/","name":"Piacere. Felicit\u00e0. - Area Prevenzione Coop.CPG23","isPartOf":{"@id":"https:\/\/cpg23.org\/area-prevenzione\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cpg23.org\/area-prevenzione\/percorso\/piacere-felicita\/#primaryimage"},"image":{"@id":"https:\/\/cpg23.org\/area-prevenzione\/percorso\/piacere-felicita\/#primaryimage"},"thumbnailUrl":"https:\/\/cpg23.org\/area-prevenzione\/wp-content\/uploads\/2024\/09\/piacere-felicita.png","datePublished":"2024-09-06T21:32:32+00:00","dateModified":"2024-09-06T21:34:49+00:00","breadcrumb":{"@id":"https:\/\/cpg23.org\/area-prevenzione\/percorso\/piacere-felicita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cpg23.org\/area-prevenzione\/percorso\/piacere-felicita\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cpg23.org\/area-prevenzione\/percorso\/piacere-felicita\/#primaryimage","url":"https:\/\/cpg23.org\/area-prevenzione\/wp-content\/uploads\/2024\/09\/piacere-felicita.png","contentUrl":"https:\/\/cpg23.org\/area-prevenzione\/wp-content\/uploads\/2024\/09\/piacere-felicita.png","width":800,"height":600,"caption":"Percorso Piacere, felicita\u0300"},{"@type":"BreadcrumbList","@id":"https:\/\/cpg23.org\/area-prevenzione\/percorso\/piacere-felicita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cpg23.org\/area-prevenzione\/"},{"@type":"ListItem","position":2,"name":"Aree Tematiche","item":"https:\/\/cpg23.org\/area-prevenzione\/percorso\/"},{"@type":"ListItem","position":3,"name":"Piacere. Felicit\u00e0."}]},{"@type":"WebSite","@id":"https:\/\/cpg23.org\/area-prevenzione\/#website","url":"https:\/\/cpg23.org\/area-prevenzione\/","name":"Area Prevenzione Coop.CPG23","description":"","publisher":{"@id":"https:\/\/cpg23.org\/area-prevenzione\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cpg23.org\/area-prevenzione\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cpg23.org\/area-prevenzione\/#organization","name":"Area Prevenzione Coop.CPG23","url":"https:\/\/cpg23.org\/area-prevenzione\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cpg23.org\/area-prevenzione\/#\/schema\/logo\/image\/","url":"https:\/\/cpg23.org\/area-prevenzione\/wp-content\/uploads\/2021\/09\/LOGO_CPG23_ORIZ-1.png","contentUrl":"https:\/\/cpg23.org\/area-prevenzione\/wp-content\/uploads\/2021\/09\/LOGO_CPG23_ORIZ-1.png","width":1593,"height":413,"caption":"Area Prevenzione Coop.CPG23"},"image":{"@id":"https:\/\/cpg23.org\/area-prevenzione\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dipend.23","https:\/\/www.instagram.com\/dipend.23\/"]}]}},"_links":{"self":[{"href":"https:\/\/cpg23.org\/area-prevenzione\/wp-json\/wp\/v2\/dt_portfolio\/15797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cpg23.org\/area-prevenzione\/wp-json\/wp\/v2\/dt_portfolio"}],"about":[{"href":"https:\/\/cpg23.org\/area-prevenzione\/wp-json\/wp\/v2\/types\/dt_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/cpg23.org\/area-prevenzione\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cpg23.org\/area-prevenzione\/wp-json\/wp\/v2\/comments?post=15797"}],"version-history":[{"count":7,"href":"https:\/\/cpg23.org\/area-prevenzione\/wp-json\/wp\/v2\/dt_portfolio\/15797\/revisions"}],"predecessor-version":[{"id":15805,"href":"https:\/\/cpg23.org\/area-prevenzione\/wp-json\/wp\/v2\/dt_portfolio\/15797\/revisions\/15805"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cpg23.org\/area-prevenzione\/wp-json\/wp\/v2\/media\/15798"}],"wp:attachment":[{"href":"https:\/\/cpg23.org\/area-prevenzione\/wp-json\/wp\/v2\/media?parent=15797"}],"wp:term":[{"taxonomy":"dt_portfolio_category","embeddable":true,"href":"https:\/\/cpg23.org\/area-prevenzione\/wp-json\/wp\/v2\/dt_portfolio_category?post=15797"},{"taxonomy":"dt_portfolio_tags","embeddable":true,"href":"https:\/\/cpg23.org\/area-prevenzione\/wp-json\/wp\/v2\/dt_portfolio_tags?post=15797"},{"taxonomy":"provincie","embeddable":true,"href":"https:\/\/cpg23.org\/area-prevenzione\/wp-json\/wp\/v2\/provincie?post=15797"},{"taxonomy":"target","embeddable":true,"href":"https:\/\/cpg23.org\/area-prevenzione\/wp-json\/wp\/v2\/target?post=15797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}