{"id":151,"count":11,"description":"","link":"https:\/\/cpg23.org\/area-prevenzione\/categoria-area-tematica\/gestione-non-violenta-del-conflitto-educazione-interculturale-inclusione\/","name":"gestione non violenta del conflitto, educazione interculturale, inclusione","slug":"gestione-non-violenta-del-conflitto-educazione-interculturale-inclusione","taxonomy":"dt_portfolio_category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>gestione non violenta del conflitto, educazione interculturale, inclusione Archivi - Area Prevenzione Coop.CPG23<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"gestione non violenta del conflitto, educazione interculturale, inclusione Archivi - Area Prevenzione Coop.CPG23\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cpg23.org\/area-prevenzione\/categoria-area-tematica\/gestione-non-violenta-del-conflitto-educazione-interculturale-inclusione\/\" \/>\n<meta property=\"og:site_name\" content=\"Area Prevenzione Coop.CPG23\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cpg23.org\/area-prevenzione\/wp-content\/uploads\/2024\/09\/slide2-home.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/categoria-area-tematica\\\/gestione-non-violenta-del-conflitto-educazione-interculturale-inclusione\\\/\",\"url\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/categoria-area-tematica\\\/gestione-non-violenta-del-conflitto-educazione-interculturale-inclusione\\\/\",\"name\":\"gestione non violenta del conflitto, educazione interculturale, inclusione Archivi - Area Prevenzione Coop.CPG23\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/categoria-area-tematica\\\/gestione-non-violenta-del-conflitto-educazione-interculturale-inclusione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/categoria-area-tematica\\\/gestione-non-violenta-del-conflitto-educazione-interculturale-inclusione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"gestione non violenta del conflitto, educazione interculturale, inclusione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/#website\",\"url\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/\",\"name\":\"Area Prevenzione Coop.CPG23\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/#organization\",\"name\":\"Area Prevenzione Coop.CPG23\",\"url\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/LOGO_CPG23_ORIZ-1.png\",\"contentUrl\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/LOGO_CPG23_ORIZ-1.png\",\"width\":1593,\"height\":413,\"caption\":\"Area Prevenzione Coop.CPG23\"},\"image\":{\"@id\":\"https:\\\/\\\/cpg23.org\\\/area-prevenzione\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dipend.23\",\"https:\\\/\\\/www.instagram.com\\\/dipend.23\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"gestione non violenta del conflitto, educazione interculturale, inclusione Archivi - Area Prevenzione Coop.CPG23","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"gestione non violenta del conflitto, educazione interculturale, inclusione Archivi - Area Prevenzione Coop.CPG23","og_url":"https:\/\/cpg23.org\/area-prevenzione\/categoria-area-tematica\/gestione-non-violenta-del-conflitto-educazione-interculturale-inclusione\/","og_site_name":"Area Prevenzione Coop.CPG23","og_image":[{"width":1500,"height":1000,"url":"https:\/\/cpg23.org\/area-prevenzione\/wp-content\/uploads\/2024\/09\/slide2-home.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/cpg23.org\/area-prevenzione\/categoria-area-tematica\/gestione-non-violenta-del-conflitto-educazione-interculturale-inclusione\/","url":"https:\/\/cpg23.org\/area-prevenzione\/categoria-area-tematica\/gestione-non-violenta-del-conflitto-educazione-interculturale-inclusione\/","name":"gestione non violenta del conflitto, educazione interculturale, inclusione Archivi - Area Prevenzione Coop.CPG23","isPartOf":{"@id":"https:\/\/cpg23.org\/area-prevenzione\/#website"},"breadcrumb":{"@id":"https:\/\/cpg23.org\/area-prevenzione\/categoria-area-tematica\/gestione-non-violenta-del-conflitto-educazione-interculturale-inclusione\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/cpg23.org\/area-prevenzione\/categoria-area-tematica\/gestione-non-violenta-del-conflitto-educazione-interculturale-inclusione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cpg23.org\/area-prevenzione\/"},{"@type":"ListItem","position":2,"name":"gestione non violenta del conflitto, educazione interculturale, inclusione"}]},{"@type":"WebSite","@id":"https:\/\/cpg23.org\/area-prevenzione\/#website","url":"https:\/\/cpg23.org\/area-prevenzione\/","name":"Area Prevenzione Coop.CPG23","description":"","publisher":{"@id":"https:\/\/cpg23.org\/area-prevenzione\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cpg23.org\/area-prevenzione\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cpg23.org\/area-prevenzione\/#organization","name":"Area Prevenzione Coop.CPG23","url":"https:\/\/cpg23.org\/area-prevenzione\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cpg23.org\/area-prevenzione\/#\/schema\/logo\/image\/","url":"https:\/\/cpg23.org\/area-prevenzione\/wp-content\/uploads\/2021\/09\/LOGO_CPG23_ORIZ-1.png","contentUrl":"https:\/\/cpg23.org\/area-prevenzione\/wp-content\/uploads\/2021\/09\/LOGO_CPG23_ORIZ-1.png","width":1593,"height":413,"caption":"Area Prevenzione Coop.CPG23"},"image":{"@id":"https:\/\/cpg23.org\/area-prevenzione\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dipend.23","https:\/\/www.instagram.com\/dipend.23\/"]}]}},"_links":{"self":[{"href":"https:\/\/cpg23.org\/area-prevenzione\/wp-json\/wp\/v2\/dt_portfolio_category\/151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cpg23.org\/area-prevenzione\/wp-json\/wp\/v2\/dt_portfolio_category"}],"about":[{"href":"https:\/\/cpg23.org\/area-prevenzione\/wp-json\/wp\/v2\/taxonomies\/dt_portfolio_category"}],"wp:post_type":[{"href":"https:\/\/cpg23.org\/area-prevenzione\/wp-json\/wp\/v2\/dt_portfolio?dt_portfolio_category=151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}